{"id":20221,"date":"2021-03-31T15:27:54","date_gmt":"2021-03-31T13:27:54","guid":{"rendered":"https:\/\/www.telelogos.com\/?page_id=20221"},"modified":"2025-03-20T17:49:26","modified_gmt":"2025-03-20T15:49:26","slug":"technological-partners","status":"publish","type":"page","link":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/","title":{"rendered":"Our technological partners"},"content":{"rendered":"<div id=\"pl-20221\"  class=\"panel-layout\" ><div id=\"pg-20221-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-20221-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-20221-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div class=\"titre_tiret_bleu h2-like\">The Telelogos partner network<\/div>\n<div><\/div>\n<div>\n<ul>\n<li>Telelogos software is designed to be able to integrate easily in many technical and business environments.<\/li>\n<li>For this reason, since it was founded, Telelogos has developed a network of leading technological partners both in hardware - processors, screens, players, mobile devices, printers, etc. - and in software - operating systems, databases, business software and technical software.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>The Telelogos partner network Telelogos software is designed to be able to integrate easily in many technical and business environments. For this reason, since it was founded, Telelogos has [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"parent":20229,"menu_order":561,"comment_status":"closed","ping_status":"closed","template":"page-partenaires.php","meta":{"footnotes":""},"class_list":["post-20221","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our technological partners - Telelogos<\/title>\n<meta name=\"description\" content=\"Explore Telelogos\u2019 network of technological partners driving innovation in digital signage, MDM, and data synchronization.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/technological-partners\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/technological-partners\\\/\",\"name\":\"Our technological partners - Telelogos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#website\"},\"datePublished\":\"2021-03-31T13:27:54+00:00\",\"dateModified\":\"2025-03-20T15:49:26+00:00\",\"description\":\"Explore Telelogos\u2019 network of technological partners driving innovation in digital signage, MDM, and data synchronization.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/technological-partners\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/technological-partners\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/technological-partners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our partners\",\"item\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/our-partners\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Our technological partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\",\"name\":\"Telelogos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#organization\",\"name\":\"Telelogos\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"contentUrl\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"width\":100,\"height\":35,\"caption\":\"Telelogos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/telelogos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our technological partners - Telelogos","description":"Explore Telelogos\u2019 network of technological partners driving innovation in digital signage, MDM, and data synchronization.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/","url":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/","name":"Our technological partners - Telelogos","isPartOf":{"@id":"https:\/\/www.telelogos.com\/en\/#website"},"datePublished":"2021-03-31T13:27:54+00:00","dateModified":"2025-03-20T15:49:26+00:00","description":"Explore Telelogos\u2019 network of technological partners driving innovation in digital signage, MDM, and data synchronization.","breadcrumb":{"@id":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.telelogos.com\/en\/our-partners\/technological-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.telelogos.com\/en\/"},{"@type":"ListItem","position":2,"name":"Our partners","item":"https:\/\/www.telelogos.com\/en\/our-partners\/"},{"@type":"ListItem","position":3,"name":"Our technological partners"}]},{"@type":"WebSite","@id":"https:\/\/www.telelogos.com\/en\/#website","url":"https:\/\/www.telelogos.com\/en\/","name":"Telelogos","description":"","publisher":{"@id":"https:\/\/www.telelogos.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.telelogos.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.telelogos.com\/en\/#organization","name":"Telelogos","url":"https:\/\/www.telelogos.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.telelogos.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","contentUrl":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","width":100,"height":35,"caption":"Telelogos"},"image":{"@id":"https:\/\/www.telelogos.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/telelogos"]}]}},"_links":{"self":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/20221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/comments?post=20221"}],"version-history":[{"count":5,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/20221\/revisions"}],"predecessor-version":[{"id":58401,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/20221\/revisions\/58401"}],"up":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/20229"}],"wp:attachment":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/media?parent=20221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}