{"id":42196,"date":"2023-03-23T15:32:12","date_gmt":"2023-03-23T13:32:12","guid":{"rendered":"https:\/\/www.telelogos.com\/?page_id=42196"},"modified":"2023-12-04T16:05:29","modified_gmt":"2023-12-04T14:05:29","slug":"confirmation-mt4d-en","status":"publish","type":"page","link":"https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/","title":{"rendered":"confirmation-mt4d-en"},"content":{"rendered":"<p>Thank you for your message.<\/p>\n<p>We acknowledge receipt and will contact you as soon as possible.<\/p>\n<p><strong>The Telelogos team<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thank you for your message. We acknowledge receipt and will contact you as soon as possible. The Telelogos team<\/p>\n","protected":false},"author":21,"featured_media":0,"parent":0,"menu_order":91,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42196","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>confirmation-mt4d-en - Telelogos<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/confirmation-mt4d-en\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/confirmation-mt4d-en\\\/\",\"name\":\"confirmation-mt4d-en - Telelogos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#website\"},\"datePublished\":\"2023-03-23T13:32:12+00:00\",\"dateModified\":\"2023-12-04T14:05:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/confirmation-mt4d-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.telelogos.com\\\/en\\\/confirmation-mt4d-en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/confirmation-mt4d-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"confirmation-mt4d-en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\",\"name\":\"Telelogos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#organization\",\"name\":\"Telelogos\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"contentUrl\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"width\":100,\"height\":35,\"caption\":\"Telelogos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/telelogos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"confirmation-mt4d-en - Telelogos","robots":{"index":"noindex","follow":"nofollow"},"twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/","url":"https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/","name":"confirmation-mt4d-en - Telelogos","isPartOf":{"@id":"https:\/\/www.telelogos.com\/en\/#website"},"datePublished":"2023-03-23T13:32:12+00:00","dateModified":"2023-12-04T14:05:29+00:00","breadcrumb":{"@id":"https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.telelogos.com\/en\/confirmation-mt4d-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.telelogos.com\/en\/"},{"@type":"ListItem","position":2,"name":"confirmation-mt4d-en"}]},{"@type":"WebSite","@id":"https:\/\/www.telelogos.com\/en\/#website","url":"https:\/\/www.telelogos.com\/en\/","name":"Telelogos","description":"","publisher":{"@id":"https:\/\/www.telelogos.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.telelogos.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.telelogos.com\/en\/#organization","name":"Telelogos","url":"https:\/\/www.telelogos.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.telelogos.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","contentUrl":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","width":100,"height":35,"caption":"Telelogos"},"image":{"@id":"https:\/\/www.telelogos.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/telelogos"]}]}},"_links":{"self":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/42196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/comments?post=42196"}],"version-history":[{"count":1,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/42196\/revisions"}],"predecessor-version":[{"id":42197,"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/pages\/42196\/revisions\/42197"}],"wp:attachment":[{"href":"https:\/\/www.telelogos.com\/en\/wp-json\/wp\/v2\/media?parent=42196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}