{"id":22663,"date":"2021-03-18T12:08:22","date_gmt":"2021-03-18T10:08:22","guid":{"rendered":"https:\/\/www.telelogos.com\/confirmation-de-votre-message-pour-leducation\/"},"modified":"2023-12-04T16:11:07","modified_gmt":"2023-12-04T14:11:07","slug":"confirmacion-de-su-mensaje-para-el-sector-educativo","status":"publish","type":"page","link":"https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/","title":{"rendered":"Confirmaci\u00f3n de su mensaje para el sector Educativo"},"content":{"rendered":"<div id=\"pl-22663\"  class=\"panel-layout\" ><div id=\"pg-22663-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-22663-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-22663-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Gracias por su mensaje.<\/p>\n<p>Lo hemos recibido y nos contactaremos a la brevedad.<\/p>\n<p><strong>El equipo de Telelogos<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Gracias por su mensaje. Lo hemos recibido y nos contactaremos a la brevedad. El equipo de Telelogos<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":143,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22663","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confirmaci\u00f3n de su mensaje para el sector Educativo - Telelogos<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/confirmacion-de-su-mensaje-para-el-sector-educativo\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/confirmacion-de-su-mensaje-para-el-sector-educativo\\\/\",\"name\":\"Confirmaci\u00f3n de su mensaje para el sector Educativo - Telelogos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#website\"},\"datePublished\":\"2021-03-18T10:08:22+00:00\",\"dateModified\":\"2023-12-04T14:11:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/confirmacion-de-su-mensaje-para-el-sector-educativo\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.telelogos.com\\\/es\\\/confirmacion-de-su-mensaje-para-el-sector-educativo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/confirmacion-de-su-mensaje-para-el-sector-educativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confirmaci\u00f3n de su mensaje para el sector Educativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/\",\"name\":\"Telelogos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#organization\",\"name\":\"Telelogos\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"contentUrl\":\"https:\\\/\\\/www.telelogos.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Telelogos-e1664355618654.png\",\"width\":100,\"height\":35,\"caption\":\"Telelogos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.telelogos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/telelogos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confirmaci\u00f3n de su mensaje para el sector Educativo - Telelogos","robots":{"index":"noindex","follow":"nofollow"},"twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/","url":"https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/","name":"Confirmaci\u00f3n de su mensaje para el sector Educativo - Telelogos","isPartOf":{"@id":"https:\/\/www.telelogos.com\/es\/#website"},"datePublished":"2021-03-18T10:08:22+00:00","dateModified":"2023-12-04T14:11:07+00:00","breadcrumb":{"@id":"https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.telelogos.com\/es\/confirmacion-de-su-mensaje-para-el-sector-educativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.telelogos.com\/es\/"},{"@type":"ListItem","position":2,"name":"Confirmaci\u00f3n de su mensaje para el sector Educativo"}]},{"@type":"WebSite","@id":"https:\/\/www.telelogos.com\/es\/#website","url":"https:\/\/www.telelogos.com\/es\/","name":"Telelogos","description":"","publisher":{"@id":"https:\/\/www.telelogos.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.telelogos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.telelogos.com\/es\/#organization","name":"Telelogos","url":"https:\/\/www.telelogos.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.telelogos.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","contentUrl":"https:\/\/www.telelogos.com\/wp-content\/uploads\/2022\/07\/Logo-Telelogos-e1664355618654.png","width":100,"height":35,"caption":"Telelogos"},"image":{"@id":"https:\/\/www.telelogos.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/telelogos"]}]}},"_links":{"self":[{"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/pages\/22663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/comments?post=22663"}],"version-history":[{"count":6,"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/pages\/22663\/revisions"}],"predecessor-version":[{"id":31939,"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/pages\/22663\/revisions\/31939"}],"wp:attachment":[{"href":"https:\/\/www.telelogos.com\/es\/wp-json\/wp\/v2\/media?parent=22663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}